{"id":976,"count":4,"description":"","link":"https:\/\/answear.cz\/blog\/tag\/timex","name":"Timex","slug":"timex","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Timex Archivy - answear.cz blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/answear.cz\/blog\/tag\/timex\" \/>\n<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Timex Archivy - answear.cz blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/answear.cz\/blog\/tag\/timex\" \/>\n<meta property=\"og:site_name\" content=\"answear.cz blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/answear.cz\/blog\/tag\/timex\",\"url\":\"https:\/\/answear.cz\/blog\/tag\/timex\",\"name\":\"Timex Archivy - answear.cz blog\",\"isPartOf\":{\"@id\":\"https:\/\/answear.cz\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/answear.cz\/blog\/tag\/timex#breadcrumb\"},\"inLanguage\":\"cs\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/answear.cz\/blog\/tag\/timex#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Dom\u016f\",\"item\":\"https:\/\/answear.cz\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Timex\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/answear.cz\/blog\/#website\",\"url\":\"https:\/\/answear.cz\/blog\/\",\"name\":\"answear.cz blog\",\"description\":\"M\u00f3da, trendy, rady a tipy stylist\u016f, novinky ze sv\u011bta m\u00f3dy. We know the ANSWEAR ;-)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/answear.cz\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"cs\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Timex Archivy - answear.cz blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/answear.cz\/blog\/tag\/timex","og_locale":"cs_CZ","og_type":"article","og_title":"Timex Archivy - answear.cz blog","og_url":"https:\/\/answear.cz\/blog\/tag\/timex","og_site_name":"answear.cz blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/answear.cz\/blog\/tag\/timex","url":"https:\/\/answear.cz\/blog\/tag\/timex","name":"Timex Archivy - answear.cz blog","isPartOf":{"@id":"https:\/\/answear.cz\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/answear.cz\/blog\/tag\/timex#breadcrumb"},"inLanguage":"cs"},{"@type":"BreadcrumbList","@id":"https:\/\/answear.cz\/blog\/tag\/timex#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Dom\u016f","item":"https:\/\/answear.cz\/blog\/"},{"@type":"ListItem","position":2,"name":"Timex"}]},{"@type":"WebSite","@id":"https:\/\/answear.cz\/blog\/#website","url":"https:\/\/answear.cz\/blog\/","name":"answear.cz blog","description":"M\u00f3da, trendy, rady a tipy stylist\u016f, novinky ze sv\u011bta m\u00f3dy. We know the ANSWEAR ;-)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/answear.cz\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"cs"}]}},"_links":{"self":[{"href":"https:\/\/answear.cz\/blog\/wp-json\/wp\/v2\/tags\/976"}],"collection":[{"href":"https:\/\/answear.cz\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/answear.cz\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/answear.cz\/blog\/wp-json\/wp\/v2\/posts?tags=976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}